{"id":2719,"date":"2023-12-13T15:55:33","date_gmt":"2023-12-13T14:55:33","guid":{"rendered":"https:\/\/iiclubiana.esteri.it\/?page_id=2719"},"modified":"2025-08-06T10:26:17","modified_gmt":"2025-08-06T08:26:17","slug":"kako-se-vpisemo","status":"publish","type":"page","link":"https:\/\/iiclubiana.esteri.it\/it\/lingua-e-cultura\/i-corsi-di-lingua\/kako-se-vpisemo\/","title":{"rendered":"Come iscriversi"},"content":{"rendered":"<div>\n<p><a href=\"https:\/\/iiclubiana.esteri.it\/it\/lingua-e-cultura\/i-corsi-di-lingua\/kako-se-vpisemo\/orari-e-prezzi\/\">ORARI E PREZZI<\/a>\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 <a href=\"https:\/\/iiclubiana.esteri.it\/it\/lingua-e-cultura\/i-corsi-di-lingua\/kako-se-vpisemo\/iscrizioni\/\">ISCRIZIONE<\/a><\/p>\n<p>Se siete interessati alla cultura italiana, studiare all\u2019IIC \u00e8 la scelta ideale. I nostri corsi privilegiano l\u2019apprendimento attivo, la riflessione linguistica e culturale, il confronto intellettuale tra studenti e insegnanti, offrendo utili strumenti per una pi\u00f9 ampia comprensione della cultura e dell\u2019arte italiane. I corsi sono divisi in livelli progressivi di apprendimento secondo quanto previsto dal Quadro Comune Europeo di Riferimento per le Lingue. La conoscenza della lingua \u00e8 valutata con un test d\u2019ingresso.<\/p>\n<p>I livelli <strong>A1<\/strong> e <strong>A2<\/strong> hanno una durata di <strong>60 ore<\/strong>, il livello <strong>B1<\/strong> di <strong>90 ore<\/strong>, mentre i livelli <strong>B2<\/strong>, <strong>C1<\/strong> e <strong>C2<\/strong> hanno una durata di <strong>120 ore<\/strong>.<\/p>\n<p>Alla fine di ogni livello \u00e8 previsto un esame per l&#8217;accesso al livello seguente; per accedervi \u00e8 in ogni caso obbligatoria la frequenza minima del 60% delle lezioni.<\/p>\n<p>Il <strong>numero massimo<\/strong> di partecipanti per ogni corso \u00e8 di <strong>10<\/strong> persone, il <strong>numero minimo<\/strong> per l&#8217;apertura di un corso \u00e8 di <strong>4<\/strong> persone.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div style=\"text-align: right;\"><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"ORARI E PREZZI\u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 \u00a0\u00a0 ISCRIZIONE Se siete interessati alla cultura italiana, studiare all\u2019IIC \u00e8 la scelta ideale. I nostri corsi privilegiano l\u2019apprendimento attivo, la riflessione linguistica e culturale, il confronto intellettuale tra studenti e insegnanti, offrendo utili strumenti per una pi\u00f9 ampia comprensione della cultura e dell\u2019arte italiane. I corsi sono [&hellip;]","protected":false},"author":6,"featured_media":0,"parent":42,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2719","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/pages\/2719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2719"}],"version-history":[{"count":6,"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/pages\/2719\/revisions"}],"predecessor-version":[{"id":5255,"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/pages\/2719\/revisions\/5255"}],"up":[{"embeddable":true,"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/pages\/42"}],"wp:attachment":[{"href":"https:\/\/iiclubiana.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}